<style type="text/css" data-type="vc_shortcodes-custom-css">.vc_custom_1658063931823{margin-top: 50px !important;}</style><div class="wpb-content-wrapper"><p>[vc_row][vc_column]

<h2 
     
    class="fc--secondary headline-single ultra"
    >
    <strong>Contatto</strong>
    </h2>

[vc_column_text el_class=&#8221;text-big&#8221;]State cercando un referente per il Vostro cantiere o avete domande su un prodotto?[/vc_column_text][vc_row_inner css=&#8221;.vc_custom_1658063931823{margin-top: 50px !important;}&#8221;][vc_column_inner]

<div  
    class="btn-wrap d-flex justify-content-start">
        
            <a href="https://www.ischebeck.de/it/contatto/"
                      class="btn bg--c2a-1"
           >
            Trova la persona di riferimento                        <i class="icon icon-chevron-right"></i>
                    </a>
        
    
        
    
        
            <a href="https://www.ischebeck.de/it/contatto/#formular"
                      class="btn bg--c2a-1"
           >
            Fai una richiesta                        <i class="icon icon-chevron-right"></i>
                    </a>
        
    
        
    
    </div>
[/vc_column_inner][/vc_row_inner][/vc_column][/vc_row]</p>
</div>{"id":3568859,"date":"2022-07-13T18:42:02","date_gmt":"2022-07-13T16:42:02","guid":{"rendered":"https:\/\/www.ischebeck.de\/the-world-of-geotechnics\/"},"modified":"2023-09-05T15:50:49","modified_gmt":"2023-09-05T13:50:49","slug":"geotecnica","status":"publish","type":"page","link":"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/","title":{"rendered":"Geotecnica"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section full_width=&#8221;stretch_row&#8221;][vc_row][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>Micropali TITAN<\/strong>\n            <br>\n        Un sistema per molte applicazioni    <\/h2>\n\n[vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Nel campo dell&#8217;ingegneria geotecnica, il micropalo TITAN offre un&#8217;ampia gamma di dimensioni per molte applicazioni diverse: dai tiranti di ancoraggio alle fondazioni e alle sottofondazioni, dalla stabilizzazione dei pendii alla chiodatura del terreno, fino alla costruzione di gallerie e all&#8217;estrazione mineraria. Gli studi di ingegneria e le imprese di fondazioni speciali di tutto il mondo sono rimasti soddisfatti dell&#8217;ampio spettro di prestazioni del nostro sistema.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1662985010985{margin-top: 40px !important;}&#8221;][vc_column]\n<div  class=\"text-plus  \">\n    <div class=\"plus-wrapper\">\n        \n\n<h2 \n     \n    class=\"headline-double\"\n    >\n    <strong>I nostri servizi<\/strong>\n            <br>\n        I Vostri vantaggi    <\/h2>\n\n        <div class=\"plus\">\n            <div><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"content bg--primary\">\n        <div>\n            <\/p>\n<ul>\n<li style=\"font-weight: 400\"><strong>il sistema autoperforante leader nel settore<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>flessibile per quasi tutte le applicazioni<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>propriet\u00e0 del prodotto rigorosamente monitorate secondo le norme pertinenti<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>alto livello di consulenza grazie all&#8217;esperienza ingegneristica<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>servizi digitali e analogici completi<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>assistenza dalla progettazione al cantiere<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>ampia gamma di corsi di formazione<\/strong><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">Il nostro sistema offre sicurezza di esecuzione e contemporaneamente efficienza economica per il Vostro progetto di costruzione. Il sistema di micropali TITAN \u00e8 conforme ai requisiti dell\u2019EC 7 e dell\u2019AASHTO. Inoltre, FRIEDR. ISCHEBECK GmbH sostiene in molti paesi il miglioramento delle normative quadro per le applicazioni geotecniche nel settore delle costruzioni.<\/p>\n<p>        <\/div>\n    <\/div>\n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1662382314178{padding-top: 0px !important;}&#8221;][vc_row][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>Il Vostro partner<\/strong>\n            <br>\n        alla pari    <\/h2>\n\n[vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Grazie alle nostre conoscenze ingegneristiche, Vi supportiamo in ogni momento per semplificare la costruzione attraverso una combinazione unica di prodotti, consulenza e assistenza.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1658501041306{background-color: #eff1f3 !important;}&#8221;][vc_row content_placement=&#8221;top&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;45327&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;]\n\n<h3 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>Il sistema<\/strong>\n            <br>\n        Micropalo TITAN    <\/h3>\n\n[vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Informazioni dettagliate su componenti, metodi ed esempi di installazione e altre caratteristiche particolari sono disponibili qui:<\/p>\n<p>[\/vc_column_text]\n\n<div  \n    class=\"btn-wrap d-flex justify-content-start\">\n        \n            <a href=\"https:\/\/www.ischebeck.de\/it\/geotecnica-con-micropalo-titan\/\"\n                      class=\"btn bg--c2a-1\"\n           >\n            PANORAMICA DEI PRODOTTI                        <i class=\"icon icon-chevron-right\"><\/i>\n                    <\/a>\n        \n    \n        \n    \n    <\/div>\n[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; el_class=&#8221;bg&#8211;gradient-2&#8243;][vc_row][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    style=\"color:#ebebeb\">\n    <strong>Applicazioni<\/strong>\n            <br>\n        Soluzioni per le pi\u00f9 varie applicazioni    <\/h2>\n\n[\/vc_column][\/vc_row][vc_row][vc_column]\n\n\n<div class=\"isch_app_group_slider isch-slider\">\n    \n    <div class=\"isch-slider-stage-wrap\">\n        \n        <div class=\"isch-slider-arrows indicator-white\"><\/div>\n        \n        <div class=\"isch-slider-stage\">\n                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/fondazioni-e-sottofondazioni\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/Strommast-Gruendung_Anwendung_555x555px-550x550.png\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Fondazioni e sottofondazioni                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/ancoraggi\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/Rueckverankerung_Anwendung_555x555px-550x550.png\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Ancoraggi                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/chiodatura-del-terreno\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/Bodenvernagelung_Anwendung_555x555px-550x550.png\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Chiodatura del terreno                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                    <\/div>\n        \n    <\/div>\n    \n    <div class=\"isch-slider-indicator indicator-white\"><\/div>\n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221;][vc_row][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>News<\/strong>\n            <br>\n        in sintesi    <\/h2>\n\n[\/vc_column][\/vc_row][vc_row][vc_column]\n<div class=\"isch-news-teaser isch-slider\">\n    \n    \n        \n    <div class=\"isch-slider-stage-wrap\">\n    \n        <div class=\"isch-slider-arrows\"><\/div>\n        \n        <div class=\"isch-slider-stage\">\n            \n                            \n            <a href=\"https:\/\/www.ischebeck.de\/it\/titan-summit-2026\/\" class=\"isch-slider-item cat-4344 cat-4400 cat-4862\">\n                \n                <div class=\"isch-slider-item-inner\">\n\n                    <div class=\"news-teaser-image\">\n                        <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2026\/07\/Gruppenfoto_TITAN_SUMMIT_V-550x375.jpg\" alt=\"Gruppenfoto TITAN-SUMMIT\">\n                    <\/div>\n                    <div class=\"news-teaser-content\">\n                        <h4>\n                            <strong>\n                                TITAN SUMMIT 2026                                                                <div class=\"subline\">Lo scambio internazionale rafforza la cooperazione globale<\/div>\n                                                            <\/strong>\n                        <\/h4>\n                        <p>Nell\u2019ambito del TITAN SUMMIT 2026, i collaboratori delle sedi internazionali del Gruppo si sono riuniti presso la sede centrale di Ennepetal, tra cui rappresentanti provenienti da Stati Uniti, Australia, [...]<\/p>\n                        <div class=\"triangle-wrap\">                        \n                            <div class=\"triangle\"><\/div>\n                            <i class=\"icon icon-plus\"><\/i>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/a>\n\n            \n                            \n            <a href=\"https:\/\/www.ischebeck.de\/it\/castello-di-leuchtenburg-germania\/\" class=\"isch-slider-item cat-4344 cat-4400\">\n                \n                <div class=\"isch-slider-item-inner\">\n\n                    <div class=\"news-teaser-image\">\n                        <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2026\/01\/Vorschaubild-550x375.jpg\" alt=\"Con l\u2019ascensore inclinato migliora l&#039;accesso al castello di Leuchtenburg\">\n                    <\/div>\n                    <div class=\"news-teaser-content\">\n                        <h4>\n                            <strong>\n                                Con l\u2019ascensore inclinato migliora l'accesso al castello di Leuchtenburg                                                                <div class=\"subline\">Fondazioni profonde, ancoraggio delle strutture e sostegno dello scavo<\/div>\n                                                            <\/strong>\n                        <\/h4>\n                        <p>Presso il castello medievale di Leuchtenburg a Seitenroda, in Turingia, Germania, \u00e8 in fase di realizzazione un moderno ascensore inclinato che faciliter\u00e0 notevolmente [...]<\/p>\n                        <div class=\"triangle-wrap\">                        \n                            <div class=\"triangle\"><\/div>\n                            <i class=\"icon icon-plus\"><\/i>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/a>\n\n            \n                            \n            <a href=\"https:\/\/www.ischebeck.de\/it\/foundazione-sicura\/\" class=\"isch-slider-item cat-4344 cat-4400\">\n                \n                <div class=\"isch-slider-item-inner\">\n\n                    <div class=\"news-teaser-image\">\n                        <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2025\/11\/Dueren_Vorschaubild-550x375.jpg\" alt=\"Fondazione sicura con il contrasto della sottospinta idraulica\">\n                    <\/div>\n                    <div class=\"news-teaser-content\">\n                        <h4>\n                            <strong>\n                                Fondazione sicura con il contrasto della sottospinta idraulica                                                                <div class=\"subline\">Impianto di depurazione delle acque reflue di D\u00fcren, Germania<\/div>\n                                                            <\/strong>\n                        <\/h4>\n                        <p>Nell'ambito della ristrutturazione e dell'ampliamento dell'impianto di depurazione delle acque reflue di D\u00fcren, Germania, i bacini di accumulo combinati sono stati modernizzati [...]<\/p>\n                        <div class=\"triangle-wrap\">                        \n                            <div class=\"triangle\"><\/div>\n                            <i class=\"icon icon-plus\"><\/i>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/a>\n\n            \n                            \n            <a href=\"https:\/\/www.ischebeck.de\/it\/16-workshop-internazionale-sui-micropali\/\" class=\"isch-slider-item cat-4344 cat-4400\">\n                \n                <div class=\"isch-slider-item-inner\">\n\n                    <div class=\"news-teaser-image\">\n                        <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2025\/10\/Group-550x375.jpg\" alt=\"16\u00b0 Workshop internazionale sui micropali\">\n                    <\/div>\n                    <div class=\"news-teaser-content\">\n                        <h4>\n                            <strong>\n                                16\u00b0 Workshop internazionale sui micropali                                                                <div class=\"subline\">Bienvenidos a Val\u00e8ncia, Espa\u00f1a!<\/div>\n                                                            <\/strong>\n                        <\/h4>\n                        <p>Il 16\u00b0 Workshop internazionale sui micropali, organizzato dalla International Society for Micropiles (ISM), si \u00e8 tenuto dal 24 al 26 settembre 2025 presso la Ciudad de las Artes y las [...]<\/p>\n                        <div class=\"triangle-wrap\">                        \n                            <div class=\"triangle\"><\/div>\n                            <i class=\"icon icon-plus\"><\/i>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/a>\n\n            \n                            \n            <a href=\"https:\/\/www.ischebeck.de\/it\/nuovo-video-golfari-per-tension-micropiles-titan\/\" class=\"isch-slider-item cat-4344 cat-4400\">\n                \n                <div class=\"isch-slider-item-inner\">\n\n                    <div class=\"news-teaser-image\">\n                        <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2025\/10\/Vorschaubild-Marc-EN-klein-550x375.jpg\" alt=\"Nuovo video: Golfari per Tension Micropiles TITAN\">\n                    <\/div>\n                    <div class=\"news-teaser-content\">\n                        <h4>\n                            <strong>\n                                Nuovo video: Golfari per Tension Micropiles TITAN                                                                <div class=\"subline\">Dalla soluzione standard all'innovazione progettuale<\/div>\n                                                            <\/strong>\n                        <\/h4>\n                        <p>Nel nostro ultimo video, Marc Mastrantuono (Responsabile della divisione Geotecnica negli USA) fornisce approfondimenti sulla gamma di applicazioni dei nostri golfari per Tension [...]<\/p>\n                        <div class=\"triangle-wrap\">                        \n                            <div class=\"triangle\"><\/div>\n                            <i class=\"icon icon-plus\"><\/i>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/a>\n\n            \n                            \n            <a href=\"https:\/\/www.ischebeck.de\/it\/new-video-titan-micropiles-geothermal-applications\/\" class=\"isch-slider-item cat-4344 cat-4400\">\n                \n                <div class=\"isch-slider-item-inner\">\n\n                    <div class=\"news-teaser-image\">\n                        <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2025\/10\/News-Titan-micropile-EN-550x375.jpg\" alt=\"Nuovo video: micropali TITAN per applicazioni geotermiche\">\n                    <\/div>\n                    <div class=\"news-teaser-content\">\n                        <h4>\n                            <strong>\n                                Nuovo video: micropali TITAN per applicazioni geotermiche                                                            <\/strong>\n                        <\/h4>\n                        <p>Nel nostro ultimo video su YouTube, Melissa Kepdib (Application Engineer per la geotecnica, Germania) mostra come i micropali TITAN possano essere utilizzati non solo per le [...]<\/p>\n                        <div class=\"triangle-wrap\">                        \n                            <div class=\"triangle\"><\/div>\n                            <i class=\"icon icon-plus\"><\/i>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/a>\n\n                    <\/div>\n    \n    <\/div>        \n        \n    <div class=\"isch-slider-indicator\">\n        \n    <\/div>\n    \n<\/div>\n\n\n[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1660747271646{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column]\n\n\n<div \n    class=\"isch-highlight-panel   \" \n        data-size-rel=\"0.25694444444444\"\n    data-size-rel-mobile=\"0\">\n    \n    \n    \n    <picture>\n        <source srcset=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/mikropfahl-titan.png\" media=\"(min-width: 768px)\">                    \n        <img decoding=\"async\" src=\"\">\n    <\/picture>    \n    \n    <div class=\"overlay  \" ><\/div>\n    \n        <div class=\"container highlight-panel-content\">\n            \n            <div class=\"higlight-panel-content-wrap\" >\n                \n                                <div class=\"highlight-panel-content-inner\">\n                    \n\n<h3 \n     \n    class=\"headline-double  text_decoration\"\n    style=\"color:#ffffff\">\n    <strong>Seminare<\/strong>\n            <br>\n        f\u00fcr Bohrh\u00e4mmer (Ger\u00e4tef\u00fchrer)    <\/h3>\n\n\n                    \n                            \n                    <a href=\"#test\" \n                       target=\"\" \n                       title=\"Mehr erfahren\" \n                       class=\"btn bg--primary\">\n                            Mehr erfahren                                                            <i class=\"icon icon-chevron-right\"><\/i>\n                                                <\/a>\n                                    <\/div>\n            <\/div>\n            \n        <\/div>\n      \n    \n    \n    \n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221;][vc_row][vc_column][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nel campo dell&#039;ingegneria geotecnica, il micropalo TITAN offre un&#039;ampia gamma di dimensioni per molte applicazioni diverse: dai tiranti di ancoraggio alle fondazioni e alle sottofondazioni, dalla stabilizzazione [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7356575,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3568859","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geotecnica con il micropalo TITAN<\/title>\n<meta name=\"description\" content=\"Nel campo della geotecnica, il sistema di micropali TITAN offre un&#039;ampia gamma di dimensioni per molte applicazioni diverse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geotecnica con il micropalo TITAN\" \/>\n<meta property=\"og:description\" content=\"Nel campo della geotecnica, il sistema di micropali TITAN offre un&#039;ampia gamma di dimensioni per molte applicazioni diverse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/\" \/>\n<meta property=\"og:site_name\" content=\"ISCHEBECK TITAN\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T13:50:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/geotecnica\\\/\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/geotecnica\\\/\",\"name\":\"Geotecnica con il micropalo TITAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#website\"},\"datePublished\":\"2022-07-13T16:42:02+00:00\",\"dateModified\":\"2023-09-05T13:50:49+00:00\",\"description\":\"Nel campo della geotecnica, il sistema di micropali TITAN offre un'ampia gamma di dimensioni per molte applicazioni diverse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/geotecnica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/geotecnica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/geotecnica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azienda\",\"item\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Geotecnica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/\",\"name\":\"ISCHEBECK TITAN\",\"description\":\"National und international f\u00fchrender Hersteller von Produkten f\u00fcr die Baubranche\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#organization\",\"name\":\"FRIEDR. ISCHEBECK GMBH\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ischebecklogo.png\",\"contentUrl\":\"https:\\\/\\\/www.ischebeck.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ischebecklogo.png\",\"width\":630,\"height\":235,\"caption\":\"FRIEDR. ISCHEBECK GMBH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWC7NNXogZGJPs-bxuk7C8A\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/friedr.-ischebeck-gmbh\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geotecnica con il micropalo TITAN","description":"Nel campo della geotecnica, il sistema di micropali TITAN offre un'ampia gamma di dimensioni per molte applicazioni diverse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/","og_locale":"it_IT","og_type":"article","og_title":"Geotecnica con il micropalo TITAN","og_description":"Nel campo della geotecnica, il sistema di micropali TITAN offre un'ampia gamma di dimensioni per molte applicazioni diverse.","og_url":"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/","og_site_name":"ISCHEBECK TITAN","article_modified_time":"2023-09-05T13:50:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/","url":"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/","name":"Geotecnica con il micropalo TITAN","isPartOf":{"@id":"https:\/\/www.ischebeck.de\/it\/#website"},"datePublished":"2022-07-13T16:42:02+00:00","dateModified":"2023-09-05T13:50:49+00:00","description":"Nel campo della geotecnica, il sistema di micropali TITAN offre un'ampia gamma di dimensioni per molte applicazioni diverse.","breadcrumb":{"@id":"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ischebeck.de\/it\/azienda\/geotecnica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ischebeck.de\/it\/"},{"@type":"ListItem","position":2,"name":"Azienda","item":"https:\/\/www.ischebeck.de\/it\/azienda\/"},{"@type":"ListItem","position":3,"name":"Geotecnica"}]},{"@type":"WebSite","@id":"https:\/\/www.ischebeck.de\/it\/#website","url":"https:\/\/www.ischebeck.de\/it\/","name":"ISCHEBECK TITAN","description":"National und international f\u00fchrender Hersteller von Produkten f\u00fcr die Baubranche","publisher":{"@id":"https:\/\/www.ischebeck.de\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ischebeck.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ischebeck.de\/it\/#organization","name":"FRIEDR. ISCHEBECK GMBH","url":"https:\/\/www.ischebeck.de\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ischebeck.de\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/ischebecklogo.png","contentUrl":"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/ischebecklogo.png","width":630,"height":235,"caption":"FRIEDR. ISCHEBECK GMBH"},"image":{"@id":"https:\/\/www.ischebeck.de\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCWC7NNXogZGJPs-bxuk7C8A","https:\/\/www.linkedin.com\/company\/friedr.-ischebeck-gmbh"]}]}},"_links":{"self":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/3568859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/comments?post=3568859"}],"version-history":[{"count":7,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/3568859\/revisions"}],"predecessor-version":[{"id":12889037,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/3568859\/revisions\/12889037"}],"up":[{"embeddable":true,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/7356575"}],"wp:attachment":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/media?parent=3568859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}