<style type="text/css" data-type="vc_shortcodes-custom-css">.vc_custom_1662209039546{margin-bottom: 30px !important;}.vc_custom_1687936703423{padding-top: 30px !important;}.vc_custom_1666528422079{padding-top: 20px !important;}</style><div class="wpb-content-wrapper"><p>[vc_row][vc_column][vc_row_inner css=&#8221;.vc_custom_1662209039546{margin-bottom: 30px !important;}&#8221;][vc_column_inner]

<h2 
     
    class="headline-double  text_decoration"
    >
    <strong>Il vostro</strong>
            <br>
        interlocutore in Italia    </h2>

[vc_column_text]Per ulteriori informazioni sui sistemi di casseforme ISCHEBECK TITAN, contattate Giorgio Severi.[/vc_column_text][/vc_column_inner][/vc_row_inner][vc_row_inner content_placement=&#8221;bottom&#8221;][vc_column_inner width=&#8221;1/3&#8243;][vc_single_image image=&#8221;9141333&#8243; img_size=&#8221;555&#215;555&#8243;][/vc_column_inner][vc_column_inner width=&#8221;2/3&#8243; css=&#8221;.vc_custom_1666528422079{padding-top: 20px !important;}&#8221;][vc_column_text]</p>
<h4 class="mb-05"><strong>FRIEDR. ISCHEBECK GmbH</strong></h4>
<p><strong>Giorgio Severi</strong></p>
<p>&nbsp;</p>
<h4 class="mb-05"><a href="tel:+390403406378">+39 040 3406378</a></h4>
<h4><a href="mailto:severi@ischebeck.de">severi@ischebeck.de</a></h4>
<p>[/vc_column_text][/vc_column_inner][/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1687936703423{padding-top: 30px !important;}&#8221;][vc_column_inner][vc_column_text]Potete altrimenti lasciare il sito italiano e utilizzare le informazioni in lingua inglese. Verrete reindirizzati al nostro sito web in lingua inglese attraverso la panoramica dei prodotti e i campi di applicazione.[/vc_column_text][/vc_column_inner][/vc_row_inner][/vc_column][/vc_row]</p>
</div><style type="text/css" data-type="vc_shortcodes-custom-css">.vc_custom_1658063931823{margin-top: 50px !important;}</style><div class="wpb-content-wrapper"><p>[vc_row][vc_column]

<h2 
     
    class="fc--secondary headline-single ultra"
    >
    <strong>Contatto</strong>
    </h2>

[vc_column_text el_class=&#8221;text-big&#8221;]State cercando un referente per il Vostro cantiere o avete domande su un prodotto?[/vc_column_text][vc_row_inner css=&#8221;.vc_custom_1658063931823{margin-top: 50px !important;}&#8221;][vc_column_inner]

<div  
    class="btn-wrap d-flex justify-content-start">
        
            <a href="https://www.ischebeck.de/it/contatto/"
                      class="btn bg--c2a-1"
           >
            Trova la persona di riferimento                        <i class="icon icon-chevron-right"></i>
                    </a>
        
    
        
    
        
            <a href="https://www.ischebeck.de/it/contatto/#formular"
                      class="btn bg--c2a-1"
           >
            Fai una richiesta                        <i class="icon icon-chevron-right"></i>
                    </a>
        
    
        
    
    </div>
[/vc_column_inner][/vc_row_inner][/vc_column][/vc_row]</p>
</div>{"id":3552103,"date":"2022-07-25T16:20:08","date_gmt":"2022-07-25T14:20:08","guid":{"rendered":"https:\/\/www.ischebeck.de\/the-world-of-formwork-systems\/"},"modified":"2023-09-05T15:52:48","modified_gmt":"2023-09-05T13:52:48","slug":"sistemi-di-casseforme","status":"publish","type":"page","link":"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/","title":{"rendered":"Sistemi di casseforme"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section][vc_row][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>Flessibile economico,<\/strong>\n            <br>\n        leggero e durevole    <\/h2>\n\n[vc_column_text]<\/p>\n<p style=\"font-weight: 400\">In qualit\u00e0 di produttore del primo puntello per casseforme in alluminio al mondo, Vi offriamo una gamma perfettamente assortita di casseforme per solai nel settore dei sistemi di casseforme, fornendo la soluzione ideale per il Vostro cantiere. Che si tratti di puntelli singoli o di impalcature complesse, i sistemi di casseforme ISCHEBECK TITAN sono utilizzati in tutto il mondo e offrono molti vantaggi a imprese di costruzione generali, subappaltatori e medie imprese del settore edile.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column]\n<div  class=\"text-plus  \">\n    <div class=\"plus-wrapper\">\n        \n\n<h2 \n     \n    class=\"headline-double\"\n    >\n    <strong>i nostri servizi<\/strong>\n            <br>\n        i Vostri vantaggi    <\/h2>\n\n        <div class=\"plus\">\n            <div><\/div>\n        <\/div>\n    <\/div>\n    <div class=\"content bg--primary\">\n        <div>\n            <\/p>\n<ul>\n<li style=\"font-weight: 400\"><strong>montaggio facile e veloce<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>minor numero di componenti (meno manodopera, meno lavoro di selezione, meno<\/strong><strong>\u00a0logistica di cantiere)<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>leggerezza ed elevata ergonomia per una maggiore sicurezza sul lavoro<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>durevole e utilizzabile per lungo tempo<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>elevata efficienza economica<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>in vendita o a noleggio<\/strong><\/li>\n<li style=\"font-weight: 400\"><strong>servizi di assistenza digitale e analogica<\/strong><\/li>\n<\/ul>\n<p style=\"font-weight: 400\">Oltre a soluzioni tecniche e trasparenti di alta qualit\u00e0, con ISCHEBECK TITAN potete contare su un ottimo rapporto qualit\u00e0-prezzo. Ulteriori prodotti come puntelli in acciaio, puntoni e altri ancora completano la nostra gamma. La documentazione tecnica e i servizi di alta qualit\u00e0 sono a Vostra disposizione, cos\u00ec come l&#8217;assistenza durante l&#8217;esecuzione.<\/p>\n<p>        <\/div>\n    <\/div>\n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1658571647422{padding-top: 0px !important;}&#8221;][vc_row][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>Il Vostro<\/strong>\n            <br>\n        partner affidabile    <\/h2>\n\n[vc_column_text]<\/p>\n<p style=\"font-weight: 400\">Siamo un&#8217;azienda di successo a livello globale che comprende le esigenze individuali dei propri clienti e garantisce una collaborazione affidabile.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1682679086060{background-color: #ffffff !important;}&#8221;][vc_row css=&#8221;.vc_custom_1682678902579{background-color: #ffffff !important;}&#8221;][vc_column][\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1658501041306{background-color: #eff1f3 !important;}&#8221;][vc_row content_placement=&#8221;top&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;46195&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;]\n\n<h3 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>ALLA RICERCA DEI PRODOTTI<\/strong>\n            <br>\n        per i sistemi di casseforme    <\/h3>\n\n[vc_column_text]<\/p>\n<div><span lang=\"IT\">Qui troverete il prodotto o il sistema adatto alle vostre esigenze specifiche:<\/span><\/div>\n<p>[\/vc_column_text]\n\n<div  \n    class=\"btn-wrap d-flex justify-content-start\">\n        \n            <a href=\"https:\/\/www.ischebeck.de\/en\/formwork-systems\/\"\n                      class=\"btn bg--c2a-1\"\n           >\n            RICERCA PRODOTTO                        <i class=\"icon icon-chevron-right\"><\/i>\n                    <\/a>\n        \n    \n        \n    \n    <\/div>\n[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; el_class=&#8221;bg&#8211;gradient-2&#8243;][vc_row][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    style=\"color:#ebebeb\">\n    <strong>Applicazioni<\/strong>\n            <br>\n        Soluzioni per le pi\u00f9 varie applicazioni    <\/h2>\n\n[\/vc_column][\/vc_row][vc_row][vc_column]\n\n\n<div class=\"isch_app_group_slider isch-slider\">\n    \n    <div class=\"isch-slider-stage-wrap\">\n        \n        <div class=\"isch-slider-arrows indicator-white\"><\/div>\n        \n        <div class=\"isch-slider-stage\">\n                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/industrial-buildings\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/768x920_Industriebau1-550x550.jpg\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Edifici industriali                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/commercial-buildings\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/768x920_Gerwerblicher_Bau1-550x550.jpg\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Edifici commerciali                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/residential-buildings\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/08\/855-855-hausbau-550x550.jpg\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Edilizia residenziale                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/power-stations\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/768x920_Kraftwerk1-550x550.jpg\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Centrali elettriche                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/tunnel-portals\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/768x920_Tunnelportal1-550x550.jpg\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Portali di gallerie                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                                            <a href=\"https:\/\/www.ischebeck.de\/it\/anwendungen\/other-civil-engineering-works\/\" class=\"isch-slider-item\">\n                    \n                    <div class=\"isch-slider-item-inner\">\n\n                        <div class=\"image\">\n                            <img decoding=\"async\" src=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/855-855-sonst-ing-bau-550x550.jpg\" alt=\"\">\n                        <\/div>\n\n\n                        <div class=\"title text-normal \">\n                            Altre opere di ingegneria civile                        <\/div>                    \n\n\n                    <\/div>\n                                <\/a>\n                                    <\/div>\n        \n    <\/div>\n    \n    <div class=\"isch-slider-indicator indicator-white\"><\/div>\n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221;][vc_row disable_element=&#8221;yes&#8221;][vc_column]\n\n<h2 \n     \n    class=\"headline-double  text_decoration\"\n    >\n    <strong>News<\/strong>\n            <br>\n        at a glance    <\/h2>\n\n[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column]\n<div class=\"isch-news-teaser isch-slider\">\n    \n    \n        \n    <div class=\"isch-slider-stage-wrap\">\n    \n        <div class=\"isch-slider-arrows\"><\/div>\n        \n        <div class=\"isch-slider-stage\">\n                    <\/div>\n    \n    <\/div>        \n        \n    <div class=\"isch-slider-indicator\">\n        \n    <\/div>\n    \n<\/div>\n\n\n[\/vc_column][\/vc_row][\/vc_section][vc_section full_width=&#8221;stretch_row&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1660747291703{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column]\n\n\n<div \n    class=\"isch-highlight-panel   \" \n        data-size-rel=\"0.25694444444444\"\n    data-size-rel-mobile=\"0\">\n    \n    \n    \n    <picture>\n        <source srcset=\"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/mikropfahl-titan.png\" media=\"(min-width: 768px)\">                    \n        <img decoding=\"async\" src=\"\">\n    <\/picture>    \n    \n    <div class=\"overlay  \" ><\/div>\n    \n        <div class=\"container highlight-panel-content\">\n            \n            <div class=\"higlight-panel-content-wrap\" >\n                \n                                <div class=\"highlight-panel-content-inner\">\n                    \n\n<h3 \n     \n    class=\"headline-double  text_decoration\"\n    style=\"color:#ffffff\">\n    <strong>Seminare<\/strong>\n            <br>\n        f\u00fcr Bohrh\u00e4mmer (Ger\u00e4tef\u00fchrer)    <\/h3>\n\n\n                    \n                            \n                    <a href=\"#test\" \n                       target=\"\" \n                       title=\"Mehr erfahren\" \n                       class=\"btn bg--primary\">\n                            Mehr erfahren                                                            <i class=\"icon icon-chevron-right\"><\/i>\n                                                <\/a>\n                                    <\/div>\n            <\/div>\n            \n        <\/div>\n      \n    \n    \n    \n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section disable_element=&#8221;yes&#8221;][vc_row][vc_column][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>In qualit\u00e0 di produttore del primo puntello per casseforme in alluminio al mondo, Vi offriamo una gamma perfettamente assortita di casseforme per solai nel settore dei sistemi [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7356575,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3552103","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il mondo dei prodotti dei sistemi di casseforme<\/title>\n<meta name=\"description\" content=\"Il mondo dei sistemi di casseforme di ISCHEBECK TITAN offre una gamma perfettamente assortita di casseforme per solai e altri prodotti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il mondo dei prodotti dei sistemi di casseforme\" \/>\n<meta property=\"og:description\" content=\"Il mondo dei sistemi di casseforme di ISCHEBECK TITAN offre una gamma perfettamente assortita di casseforme per solai e altri prodotti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/\" \/>\n<meta property=\"og:site_name\" content=\"ISCHEBECK TITAN\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T13:52:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/sistemi-di-casseforme\\\/\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/sistemi-di-casseforme\\\/\",\"name\":\"Il mondo dei prodotti dei sistemi di casseforme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#website\"},\"datePublished\":\"2022-07-25T14:20:08+00:00\",\"dateModified\":\"2023-09-05T13:52:48+00:00\",\"description\":\"Il mondo dei sistemi di casseforme di ISCHEBECK TITAN offre una gamma perfettamente assortita di casseforme per solai e altri prodotti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/sistemi-di-casseforme\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/sistemi-di-casseforme\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/sistemi-di-casseforme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azienda\",\"item\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/azienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sistemi di casseforme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/\",\"name\":\"ISCHEBECK TITAN\",\"description\":\"National und international f\u00fchrender Hersteller von Produkten f\u00fcr die Baubranche\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#organization\",\"name\":\"FRIEDR. ISCHEBECK GMBH\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ischebeck.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ischebecklogo.png\",\"contentUrl\":\"https:\\\/\\\/www.ischebeck.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ischebecklogo.png\",\"width\":630,\"height\":235,\"caption\":\"FRIEDR. ISCHEBECK GMBH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ischebeck.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWC7NNXogZGJPs-bxuk7C8A\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/friedr.-ischebeck-gmbh\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il mondo dei prodotti dei sistemi di casseforme","description":"Il mondo dei sistemi di casseforme di ISCHEBECK TITAN offre una gamma perfettamente assortita di casseforme per solai e altri prodotti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/","og_locale":"it_IT","og_type":"article","og_title":"Il mondo dei prodotti dei sistemi di casseforme","og_description":"Il mondo dei sistemi di casseforme di ISCHEBECK TITAN offre una gamma perfettamente assortita di casseforme per solai e altri prodotti.","og_url":"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/","og_site_name":"ISCHEBECK TITAN","article_modified_time":"2023-09-05T13:52:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/","url":"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/","name":"Il mondo dei prodotti dei sistemi di casseforme","isPartOf":{"@id":"https:\/\/www.ischebeck.de\/it\/#website"},"datePublished":"2022-07-25T14:20:08+00:00","dateModified":"2023-09-05T13:52:48+00:00","description":"Il mondo dei sistemi di casseforme di ISCHEBECK TITAN offre una gamma perfettamente assortita di casseforme per solai e altri prodotti.","breadcrumb":{"@id":"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ischebeck.de\/it\/azienda\/sistemi-di-casseforme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ischebeck.de\/it\/"},{"@type":"ListItem","position":2,"name":"Azienda","item":"https:\/\/www.ischebeck.de\/it\/azienda\/"},{"@type":"ListItem","position":3,"name":"Sistemi di casseforme"}]},{"@type":"WebSite","@id":"https:\/\/www.ischebeck.de\/it\/#website","url":"https:\/\/www.ischebeck.de\/it\/","name":"ISCHEBECK TITAN","description":"National und international f\u00fchrender Hersteller von Produkten f\u00fcr die Baubranche","publisher":{"@id":"https:\/\/www.ischebeck.de\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ischebeck.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ischebeck.de\/it\/#organization","name":"FRIEDR. ISCHEBECK GMBH","url":"https:\/\/www.ischebeck.de\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ischebeck.de\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/ischebecklogo.png","contentUrl":"https:\/\/www.ischebeck.de\/wp-content\/uploads\/2022\/07\/ischebecklogo.png","width":630,"height":235,"caption":"FRIEDR. ISCHEBECK GMBH"},"image":{"@id":"https:\/\/www.ischebeck.de\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCWC7NNXogZGJPs-bxuk7C8A","https:\/\/www.linkedin.com\/company\/friedr.-ischebeck-gmbh"]}]}},"_links":{"self":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/3552103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/comments?post=3552103"}],"version-history":[{"count":8,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/3552103\/revisions"}],"predecessor-version":[{"id":12951940,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/3552103\/revisions\/12951940"}],"up":[{"embeddable":true,"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/pages\/7356575"}],"wp:attachment":[{"href":"https:\/\/www.ischebeck.de\/it\/wp-json\/wp\/v2\/media?parent=3552103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}